{"id":7042,"date":"2016-07-06T14:12:27","date_gmt":"2016-07-06T12:12:27","guid":{"rendered":"http:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png"},"modified":"2016-07-06T14:12:27","modified_gmt":"2016-07-06T12:12:27","slug":"vip-3","status":"inherit","type":"attachment","link":"https:\/\/aderen.es\/es\/con-quien-trabajamos-aderen-consulting\/vip-3\/","title":{"rendered":"vip"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-7042","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>vip - Aderen<\/title>\n<meta name=\"description\" content=\"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"vip - Aderen\" \/>\n<meta property=\"og:description\" content=\"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png\" \/>\n<meta property=\"og:site_name\" content=\"Aderen\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png\" \/>\n\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/vip.png\",\"url\":\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/vip.png\",\"name\":\"vip - Aderen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aderen.es\\\/#website\"},\"datePublished\":\"2016-07-06T12:12:27+00:00\",\"description\":\"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/vip.png#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/vip.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/vip.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aderen.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con qui\u00e9n trabajamos\",\"item\":\"https:\\\/\\\/aderen.es\\\/es\\\/con-quien-trabajamos-aderen-consulting\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"vip\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aderen.es\\\/#website\",\"url\":\"https:\\\/\\\/aderen.es\\\/\",\"name\":\"Aderen\",\"description\":\"Consultora especializada en la externalizaci\u00f3n de profesionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/aderen.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aderen.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aderen.es\\\/#organization\",\"name\":\"Aderen\",\"url\":\"https:\\\/\\\/aderen.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aderen.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/aderen.vl22085.dinaserver.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/aderen-white.svg\",\"contentUrl\":\"http:\\\/\\\/aderen.vl22085.dinaserver.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/aderen-white.svg\",\"width\":1,\"height\":1,\"caption\":\"Aderen\"},\"image\":{\"@id\":\"https:\\\/\\\/aderen.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"vip - Aderen","description":"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png","og_locale":"es_ES","og_type":"article","og_title":"vip - Aderen","og_description":"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud","og_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png","og_site_name":"Aderen","og_image":[{"width":380,"height":360,"url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png","url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png","name":"vip - Aderen","isPartOf":{"@id":"https:\/\/aderen.es\/#website"},"datePublished":"2016-07-06T12:12:27+00:00","description":"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud","breadcrumb":{"@id":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aderen.es\/es\/"},{"@type":"ListItem","position":2,"name":"Con qui\u00e9n trabajamos","item":"https:\/\/aderen.es\/es\/con-quien-trabajamos-aderen-consulting\/"},{"@type":"ListItem","position":3,"name":"vip"}]},{"@type":"WebSite","@id":"https:\/\/aderen.es\/#website","url":"https:\/\/aderen.es\/","name":"Aderen","description":"Consultora especializada en la externalizaci\u00f3n de profesionales","publisher":{"@id":"https:\/\/aderen.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aderen.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aderen.es\/#organization","name":"Aderen","url":"https:\/\/aderen.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aderen.es\/#\/schema\/logo\/image\/","url":"http:\/\/aderen.vl22085.dinaserver.com\/wp-content\/uploads\/2016\/10\/aderen-white.svg","contentUrl":"http:\/\/aderen.vl22085.dinaserver.com\/wp-content\/uploads\/2016\/10\/aderen-white.svg","width":1,"height":1,"caption":"Aderen"},"image":{"@id":"https:\/\/aderen.es\/#\/schema\/logo\/image\/"}}]}},"smush":{"stats":{"percent":35.097187486288448,"bytes":15998,"size_before":45582,"size_after":29584,"time":0.33000000000000002,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"thumbnail":{"percent":30.359999999999999,"bytes":1781,"size_before":5867,"size_after":4086,"time":0.029999999999999999},"medium":{"percent":33.920000000000002,"bytes":7288,"size_before":21483,"size_after":14195,"time":0.12},"blog-widget":{"percent":33.329999999999998,"bytes":522,"size_before":1566,"size_after":1044,"time":0.01},"portfolio-widget":{"percent":32.990000000000002,"bytes":1187,"size_before":3598,"size_after":2411,"time":0.029999999999999999},"full":{"percent":39.939999999999998,"bytes":5220,"size_before":13068,"size_after":7848,"time":0.14000000000000001}}},"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png\" rel=\"prettyPhoto[gallery-byTk]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"284\" src=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip-300x284.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip-300x284.png 300w, https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png 380w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":380,"height":360,"file":"2016\/06\/vip.png","sizes":{"thumbnail":{"file":"vip-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip-150x150.png"},"medium":{"file":"vip-300x284.png","width":300,"height":284,"mime_type":"image\/png","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip-300x284.png"},"blog-widget":{"file":"vip-50x50.png","width":50,"height":50,"mime_type":"image\/png","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip-50x50.png"},"portfolio-widget":{"file":"vip-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip-100x100.png"},"full":{"file":"vip.png","width":380,"height":360,"mime_type":"image\/png","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6622,"source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/vip.png","_links":{"self":[{"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/media\/7042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/comments?post=7042"}]}}