{"id":6427,"date":"2016-06-09T12:07:34","date_gmt":"2016-06-09T12:07:34","guid":{"rendered":"http:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg"},"modified":"2016-07-25T01:06:02","modified_gmt":"2016-07-24T23:06:02","slug":"u1068-2","status":"inherit","type":"attachment","link":"https:\/\/aderen.es\/es\/aderen-people\/u1068-2\/","title":{"rendered":"u1068"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-6427","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>u1068 - Aderen<\/title>\n<meta name=\"description\" content=\"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"u1068 - Aderen\" \/>\n<meta property=\"og:description\" content=\"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Aderen\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-24T23:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/u1068-1.jpg\",\"url\":\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/u1068-1.jpg\",\"name\":\"u1068 - Aderen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aderen.es\\\/#website\"},\"datePublished\":\"2016-06-09T12:07:34+00:00\",\"dateModified\":\"2016-07-24T23:06:02+00:00\",\"description\":\"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/u1068-1.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/u1068-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aderen.es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/u1068-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aderen.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aderen People\",\"item\":\"https:\\\/\\\/aderen.es\\\/es\\\/aderen-people\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"u1068\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aderen.es\\\/#website\",\"url\":\"https:\\\/\\\/aderen.es\\\/\",\"name\":\"Aderen\",\"description\":\"Consultora especializada en la externalizaci\u00f3n de profesionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/aderen.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aderen.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aderen.es\\\/#organization\",\"name\":\"Aderen\",\"url\":\"https:\\\/\\\/aderen.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aderen.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/aderen.vl22085.dinaserver.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/aderen-white.svg\",\"contentUrl\":\"http:\\\/\\\/aderen.vl22085.dinaserver.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/aderen-white.svg\",\"width\":1,\"height\":1,\"caption\":\"Aderen\"},\"image\":{\"@id\":\"https:\\\/\\\/aderen.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"u1068 - Aderen","description":"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg","og_locale":"es_ES","og_type":"article","og_title":"u1068 - Aderen","og_description":"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud","og_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg","og_site_name":"Aderen","article_modified_time":"2016-07-24T23:06:02+00:00","og_image":[{"width":1000,"height":662,"url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg","url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg","name":"u1068 - Aderen","isPartOf":{"@id":"https:\/\/aderen.es\/#website"},"datePublished":"2016-06-09T12:07:34+00:00","dateModified":"2016-07-24T23:06:02+00:00","description":"Aderen Consulting, Aderen, Freelance, specialist, especialista, expert, experto, Technology, Tecnolog\u00eda, Selecci\u00f3n, Talento, Recruiting, Talent, Headhunting, Headhunter, HR, RRHH, Customer experience, CRM, UX, Marketing Automation, Billing, Facturaci\u00f3n, Business Intelligence, BI, Big Data, Integration, Integraci\u00f3n, BPM, Mobility, Movilidad, Cloud","breadcrumb":{"@id":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aderen.es\/es\/"},{"@type":"ListItem","position":2,"name":"Aderen People","item":"https:\/\/aderen.es\/es\/aderen-people\/"},{"@type":"ListItem","position":3,"name":"u1068"}]},{"@type":"WebSite","@id":"https:\/\/aderen.es\/#website","url":"https:\/\/aderen.es\/","name":"Aderen","description":"Consultora especializada en la externalizaci\u00f3n de profesionales","publisher":{"@id":"https:\/\/aderen.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aderen.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aderen.es\/#organization","name":"Aderen","url":"https:\/\/aderen.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aderen.es\/#\/schema\/logo\/image\/","url":"http:\/\/aderen.vl22085.dinaserver.com\/wp-content\/uploads\/2016\/10\/aderen-white.svg","contentUrl":"http:\/\/aderen.vl22085.dinaserver.com\/wp-content\/uploads\/2016\/10\/aderen-white.svg","width":1,"height":1,"caption":"Aderen"},"image":{"@id":"https:\/\/aderen.es\/#\/schema\/logo\/image\/"}}]}},"smush":{"stats":{"percent":6.1063172944317223,"bytes":38610,"size_before":632296,"size_after":593686,"time":0.67000000000000004,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"thumbnail":{"percent":6.2800000000000002,"bytes":393,"size_before":6256,"size_after":5863,"time":0.040000000000000001},"medium":{"percent":5.1399999999999997,"bytes":760,"size_before":14797,"size_after":14037,"time":0.040000000000000001},"medium_large":{"percent":5.4400000000000004,"bytes":4289,"size_before":78803,"size_after":74514,"time":0.070000000000000007},"blog-widget":{"percent":7.7000000000000002,"bytes":125,"size_before":1624,"size_after":1499,"time":0.01},"portfolio-thumb":{"percent":5.8600000000000003,"bytes":3053,"size_before":52084,"size_after":49031,"time":0.11},"portfolio-widget":{"percent":7,"bytes":253,"size_before":3613,"size_after":3360,"time":0.029999999999999999},"wide":{"percent":5.6299999999999999,"bytes":6536,"size_before":116086,"size_after":109550,"time":0.089999999999999997},"regular":{"percent":5.21,"bytes":2383,"size_before":45739,"size_after":43356,"time":0.050000000000000003},"tall":{"percent":4.7199999999999998,"bytes":2737,"size_before":57997,"size_after":55260,"time":0.029999999999999999},"wide_tall":{"percent":7.5999999999999996,"bytes":10259,"size_before":134946,"size_after":124687,"time":0.059999999999999998},"full":{"percent":6.5,"bytes":7822,"size_before":120351,"size_after":112529,"time":0.14000000000000001}}},"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg\" rel=\"prettyPhoto[gallery-tL4g]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"Desarrollo de una BAM\" srcset=\"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-300x199.jpg 300w, https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-768x508.jpg 768w, https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Desarrollo de una BAM<\/p>\n"},"alt_text":"Desarrollo de una BAM","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":662,"file":"2016\/06\/u1068-1.jpg","sizes":{"thumbnail":{"file":"u1068-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-150x150.jpg"},"medium":{"file":"u1068-1-300x199.jpg","width":300,"height":199,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-300x199.jpg"},"medium_large":{"file":"u1068-1-768x508.jpg","width":768,"height":508,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-768x508.jpg"},"blog-widget":{"file":"u1068-1-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-50x50.jpg"},"portfolio-thumb":{"file":"u1068-1-600x403.jpg","width":600,"height":403,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-600x403.jpg"},"portfolio-widget":{"file":"u1068-1-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-100x100.jpg"},"wide":{"file":"u1068-1-1000x500.jpg","width":1000,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-1000x500.jpg"},"regular":{"file":"u1068-1-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-500x500.jpg"},"tall":{"file":"u1068-1-500x662.jpg","width":500,"height":662,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-500x662.jpg"},"wide_tall":{"file":"u1068-1-1000x662.jpg","width":1000,"height":662,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1-1000x662.jpg"},"full":{"file":"u1068-1.jpg","width":1000,"height":662,"mime_type":"image\/jpeg","source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6223,"source_url":"https:\/\/aderen.es\/wp-content\/uploads\/2016\/06\/u1068-1.jpg","_links":{"self":[{"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/media\/6427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aderen.es\/es\/wp-json\/wp\/v2\/comments?post=6427"}]}}